{"id":5,"count":1,"description":"","link":"http:\/\/macmillanadvertising.com\/index.php\/category\/novos-casinos-pt\/","name":"novos-casinos-pt","slug":"novos-casinos-pt","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"http:\/\/macmillanadvertising.com\/index.php\/wp-json\/wp\/v2\/categories\/5","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/macmillanadvertising.com\/index.php\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"http:\/\/macmillanadvertising.com\/index.php\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"http:\/\/macmillanadvertising.com\/index.php\/wp-json\/wp\/v2\/posts?categories=5"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}